{"id":2716,"date":"2010-01-25T11:32:20","date_gmt":"2010-01-25T09:32:20","guid":{"rendered":"https:\/\/xnet-x.net\/stop-acta-2\/"},"modified":"2010-01-25T11:32:20","modified_gmt":"2010-01-25T09:32:20","slug":"stop-acta-2","status":"publish","type":"post","link":"https:\/\/xnet-x.net\/ca\/stop-acta-2\/","title":{"rendered":"[Untitled]"},"content":{"rendered":"<p>[Per falta de temps i recursos, la traducci\u00f3 al catal\u00e0 d'aquesta web no est\u00e0 acabada. Si trobes interessants alguns dels nostres documents i tens temps de traduir-los, ens ho pot enviar (si us plau, reproduint la maquetaci\u00f3). Moltes gr\u00e0cies!]<\/p>\n<h3 style=\"text-align: justify;\">Se buscan amigos (norte) americanos<\/h3>\n<p style=\"text-align: justify;\"><strong>Comunicado de Red SOStenible<\/strong><\/p>\n<p style=\"text-align: justify;\">(Contiene al final una nota)<\/p>\n<p style=\"text-align: justify;\">Ma\u00f1ana martes 26 tendr\u00e1 lugar en Ciudad de M\u00e9xico una de las rondas de conversaciones sobre <a href=\"http:\/\/www.internautas.org\/html\/5886.html\" target=\"_blank\" rel=\"noopener noreferrer\">el temido Acuerdo Comercial Anti-Falsificaci\u00f3n (ACTA)<\/a>, un acuerdo entre estados y multinacionales realizado al margen de los parlamentos soberanos y cuyo texto \u00edntegro se mantiene en secreto a pesar de las repetidas <a href=\"http:\/\/www.michaelgeist.ca\/content\/view\/4671\/125\/\" target=\"_blank\" rel=\"noopener noreferrer\">demandas a nivel internacional por parte de parlamentarios<\/a> y organizaciones por la defensa de los derechos civiles en la era digital.<\/p>\n<p style=\"text-align: justify;\">ACTA versa no s\u00f3lo sobre propiedad intelectual, sino tambi\u00e9n sobre patentes y marcas, incluyendo aquellas patentes con una elevada carga social, como las manipulaciones gen\u00e9ticas, los productos transg\u00e9nicos, las patentes de software, modelos de negocio impuestos, etc.)<\/p>\n<p style=\"text-align: justify;\">ACTA es la madre del cordero, es el ejemplo, la Carta Magna que utiliza la industria del entretenimiento y de las patentes para forzar las legislaciones de cada pa\u00eds, incluido Espa\u00f1a.<br \/>\nA pesar de que la administraci\u00f3n Obama esta demostrando una cierta apertura en la defensa de una Internet abierta y neutral, ACTA\u00a0 es lo que ha impulsado al anterior embajador americano en Espa\u00f1a a ser la primera persona en \"reprender\" a Zapatero tras su intervenci\u00f3n p\u00fablica para dar marcha atr\u00e1s en la primera versi\u00f3n de la LES.<br \/>\nACTA es la espada de Damocles a nivel mundial sobre los derechos civiles de la era digital.<\/p>\n<p style=\"text-align: justify;\">Por ello la primera persona a la que ha pedido un encuentro la RED SOStenible ha sido al embajador americano, Alan Solomont.<\/p>\n<p style=\"text-align: justify;\">Todav\u00eda no hemos recibido respuesta.<br \/>\nRED SOStenible, busca a ciudadanas y ciudadanos americanos que apadrinen su petici\u00f3n de cita.<br \/>\nPuedes escribirnos a: contacto(a)RED-SOStenible.net<\/p>\n<p style=\"text-align: justify;\">Por \u00faltimo celebramos<a href=\"http:\/\/bit.ly\/80bnNl\" target=\"_blank\" rel=\"noopener noreferrer\"> las conclusiones del informe de la CNC<\/a> que corroboran lo que la sociedad civil viene diciendo desde hace mucho tiempo y que est\u00e1 detalladamente manifestado de forma propositiva en lo que es nuestra Carta Magna, <a href=\"http:\/\/fcforum.net\/es\/\" target=\"_blank\" rel=\"noopener noreferrer\">la Carta por la Innovaci\u00f3n, la Creatividad y el Acceso al Conocimiento<\/a>: que las entidades de gesti\u00f3n son un monopolio que dificulta la libre circulaci\u00f3n de la cultura y el beneficio de las autoras y autores y que tienen que ser reformadas.<\/p>\n<p style=\"text-align: justify;\">Seguimos...<\/p>\n<p style=\"text-align: justify;\">Red SOStenible<\/p>\n<p style=\"text-align: justify;\">ADJUNTO:<br \/>\nDesc\u00e1rgate <a href=\"http:\/\/www.impi.gob.mx\/\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a> el resumen de ACTA ofrecido por el instituto mexicano de la propiedad industrial (). [\u201cTodo el que entre al auditorio deber\u00e1 firmar un acuerdo de confidencialidad y presentar una identificaci\u00f3n oficial.\u00a0 No se podr\u00e1n introducir celulares ni aparatos de localizaci\u00f3n al recinto\".]<br \/>\nTendr\u00e1s que contentarte con <a href=\"http:\/\/www.impi.gob.mx\/work\/sites\/IMPI\/resources\/LocalContent\/474\/24\/Final_Spanish.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">el resumen<\/a>, el texto completo s\u00f3lo lo tienen... Ellos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[Per falta de temps i recursos, la traducci\u00f3 al catal\u00e0  [&#8230;]<\/p>\n","protected":false},"author":5,"featured_media":2715,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luchas-por-las-libertades-civiles"],"acf":[],"_links":{"self":[{"href":"https:\/\/xnet-x.net\/ca\/wp-json\/wp\/v2\/posts\/2716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xnet-x.net\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xnet-x.net\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xnet-x.net\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/xnet-x.net\/ca\/wp-json\/wp\/v2\/comments?post=2716"}],"version-history":[{"count":0,"href":"https:\/\/xnet-x.net\/ca\/wp-json\/wp\/v2\/posts\/2716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xnet-x.net\/ca\/wp-json\/wp\/v2\/media\/2715"}],"wp:attachment":[{"href":"https:\/\/xnet-x.net\/ca\/wp-json\/wp\/v2\/media?parent=2716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xnet-x.net\/ca\/wp-json\/wp\/v2\/categories?post=2716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xnet-x.net\/ca\/wp-json\/wp\/v2\/tags?post=2716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}